{"id":2199,"date":"2023-01-13T20:17:05","date_gmt":"2023-01-13T19:17:05","guid":{"rendered":"http:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg"},"modified":"2023-01-13T20:17:05","modified_gmt":"2023-01-13T19:17:05","slug":"uroczystoci_pogrzebowe_p-_generaa_jana_podhorskiego_12","status":"inherit","type":"attachment","link":"https:\/\/liceum.kard.hlonda.pl\/index.php\/2023\/01\/13\/uroczystosci-pogrzebowe-sp-generala-jana-podhorskiego\/uroczystoci_pogrzebowe_p-_generaa_jana_podhorskiego_12\/","title":{"rendered":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2199","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-300x225.jpg 300w, https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-467x350.jpg 467w, https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":480,"file":"2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg","filesize":127579,"sizes":{"medium":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-300x225.jpg","width":300,"height":225,"filesize":21408,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-300x225.jpg"},"thumbnail":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-150x150.jpg","width":150,"height":150,"filesize":7966,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-150x150.jpg"},"post-thumbnail":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-467x350.jpg","width":467,"height":350,"filesize":46930,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-467x350.jpg"},"anima-featured":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-621x350.jpg","width":621,"height":350,"filesize":63010,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-621x350.jpg"},"anima-featured-lp":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-640x350.jpg","width":640,"height":350,"filesize":74925,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-640x350.jpg"},"anima-featured-half":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-640x350.jpg","width":640,"height":350,"filesize":74925,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-640x350.jpg"},"anima-featured-third":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-512x350.jpg","width":512,"height":350,"filesize":51282,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-512x350.jpg"},"anima-lpbox-1":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-480x350.jpg","width":480,"height":350,"filesize":47635,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-480x350.jpg"},"anima-lpbox-2":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-640x400.jpg","width":640,"height":400,"filesize":90547,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12-640x400.jpg"},"full":{"file":"uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg","width":640,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2187,"source_url":"https:\/\/liceum.kard.hlonda.pl\/wp-content\/uploads\/2023\/01\/uroczystoci_pogrzebowe_p._generaa_jana_podhorskiego_12.jpg","_links":{"self":[{"href":"https:\/\/liceum.kard.hlonda.pl\/index.php\/wp-json\/wp\/v2\/media\/2199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liceum.kard.hlonda.pl\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/liceum.kard.hlonda.pl\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/liceum.kard.hlonda.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/liceum.kard.hlonda.pl\/index.php\/wp-json\/wp\/v2\/comments?post=2199"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2187,"href":"https:\/\/liceum.kard.hlonda.pl\/index.php\/wp-json\/wp\/v2\/posts\/2187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}